{"id":18,"count":21,"description":"","link":"https:\/\/elclubdelosquesos.com\/tienda\/product-category\/quesos\/","name":"Quesos","slug":"quesos","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/elclubdelosquesos.com\/tienda\/wp-json\/wp\/v2\/product_cat\/18","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elclubdelosquesos.com\/tienda\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elclubdelosquesos.com\/tienda\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/elclubdelosquesos.com\/tienda\/wp-json\/wp\/v2\/product?product_cat=18"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}